{"id":3059,"date":"2014-08-25T10:05:59","date_gmt":"2014-08-25T07:05:59","guid":{"rendered":"https:\/\/meiren.ee\/?p=3059"},"modified":"2014-08-25T10:05:59","modified_gmt":"2014-08-25T07:05:59","slug":"in-taspo-august-2014","status":"publish","type":"post","link":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/","title":{"rendered":"In Taspo August 2014"},"content":{"rendered":"<p>Das estnische Unternehmen Meiren Engineering O\u00dc wurde im Mai 2014 mit dem Preis der Deutschen Wirtschaft (Schwerpunkt &#8222;Innovation&#8220;) ausgezeichnet. F\u00fcr Meiren Engineering ist es die sechste Auszeichnung in den letzten beiden Jahren.<\/p>\n<p><a href=\"https:\/\/meiren.ee\/wp-content\/uploads\/2014\/08\/Taspo-15.08.2014.pdf\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/meiren.ee\/wp-content\/uploads\/2014\/08\/Ausgezeichneter-Este-Schneer\u00e4umer-Taspo-15.08.2014-nr-33-330x720.jpg\" alt=\"Ausgezeichneter Este Schneer\u00e4umer Taspo 15.08.2014 nr 33\" width=\"330\" height=\"720\" class=\"alignnone size-large wp-image-3060\" srcset=\"https:\/\/www.meiren.ee\/wp-content\/uploads\/2014\/08\/Ausgezeichneter-Este-Schneer\u00e4umer-Taspo-15.08.2014-nr-33-330x720.jpg 330w, https:\/\/www.meiren.ee\/wp-content\/uploads\/2014\/08\/Ausgezeichneter-Este-Schneer\u00e4umer-Taspo-15.08.2014-nr-33-137x300.jpg 137w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das estnische Unternehmen Meiren Engineering O\u00dc wurde im Mai 2014 mit dem Preis der Deutschen Wirtschaft (Schwerpunkt &#8222;Innovation&#8220;) ausgezeichnet. F\u00fcr Meiren Engineering ist es die sechste Auszeichnung in den letzten beiden Jahren.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":["post-3059","post","type-post","status-publish","format-standard","hentry","category-artikel-in-der-presse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Taspo August 2014 | Meiren lumesahad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Taspo August 2014 | Meiren lumesahad\" \/>\n<meta property=\"og:description\" content=\"Das estnische Unternehmen Meiren Engineering O\u00dc wurde im Mai 2014 mit dem Preis der Deutschen Wirtschaft (Schwerpunkt &#8222;Innovation&#8220;) ausgezeichnet. F\u00fcr Meiren Engineering ist es die sechste Auszeichnung in den letzten beiden Jahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"Meiren lumesahad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Meiren.ee?ref=nf\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-25T07:05:59+00:00\" \/>\n<meta name=\"author\" content=\"Liisi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liisi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/\"},\"author\":{\"name\":\"Liisi\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/#\\\/schema\\\/person\\\/6ff02eb9c3982cffdbba1fddf24d530e\"},\"headline\":\"In Taspo August 2014\",\"datePublished\":\"2014-08-25T07:05:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/\"},\"wordCount\":35,\"articleSection\":[\"Artikel in der Presse\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/\",\"url\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/\",\"name\":\"In Taspo August 2014 | Meiren lumesahad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/#website\"},\"datePublished\":\"2014-08-25T07:05:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/#\\\/schema\\\/person\\\/6ff02eb9c3982cffdbba1fddf24d530e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/neuigkeiten\\\/artikel-in-der-presse\\\/in-taspo-august-2014\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Taspo August 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/\",\"name\":\"Meiren lumesahad\",\"description\":\"Lumesahk ja lumet\u00f5rje tehnika, maantee lumesahk, lumesahk traktorile, lumesahk maasturile, harjad, lumekopp, varuosad ja hooldus, lumesaha terad, Kobit s.r.o. soolapuisturid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.meiren.ee\\\/en\\\/#\\\/schema\\\/person\\\/6ff02eb9c3982cffdbba1fddf24d530e\",\"name\":\"Liisi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g\",\"caption\":\"Liisi\"},\"url\":\"https:\\\/\\\/www.meiren.ee\\\/de\\\/author\\\/liisi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Taspo August 2014 | Meiren lumesahad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/","og_locale":"de_DE","og_type":"article","og_title":"In Taspo August 2014 | Meiren lumesahad","og_description":"Das estnische Unternehmen Meiren Engineering O\u00dc wurde im Mai 2014 mit dem Preis der Deutschen Wirtschaft (Schwerpunkt &#8222;Innovation&#8220;) ausgezeichnet. F\u00fcr Meiren Engineering ist es die sechste Auszeichnung in den letzten beiden Jahren.","og_url":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/","og_site_name":"Meiren lumesahad","article_publisher":"https:\/\/www.facebook.com\/Meiren.ee?ref=nf","article_published_time":"2014-08-25T07:05:59+00:00","author":"Liisi","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Liisi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/#article","isPartOf":{"@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/"},"author":{"name":"Liisi","@id":"https:\/\/www.meiren.ee\/en\/#\/schema\/person\/6ff02eb9c3982cffdbba1fddf24d530e"},"headline":"In Taspo August 2014","datePublished":"2014-08-25T07:05:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/"},"wordCount":35,"articleSection":["Artikel in der Presse"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/","url":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/","name":"In Taspo August 2014 | Meiren lumesahad","isPartOf":{"@id":"https:\/\/www.meiren.ee\/en\/#website"},"datePublished":"2014-08-25T07:05:59+00:00","author":{"@id":"https:\/\/www.meiren.ee\/en\/#\/schema\/person\/6ff02eb9c3982cffdbba1fddf24d530e"},"breadcrumb":{"@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.meiren.ee\/de\/neuigkeiten\/artikel-in-der-presse\/in-taspo-august-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.meiren.ee\/en\/"},{"@type":"ListItem","position":2,"name":"In Taspo August 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.meiren.ee\/en\/#website","url":"https:\/\/www.meiren.ee\/en\/","name":"Meiren lumesahad","description":"Lumesahk ja lumet\u00f5rje tehnika, maantee lumesahk, lumesahk traktorile, lumesahk maasturile, harjad, lumekopp, varuosad ja hooldus, lumesaha terad, Kobit s.r.o. soolapuisturid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.meiren.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.meiren.ee\/en\/#\/schema\/person\/6ff02eb9c3982cffdbba1fddf24d530e","name":"Liisi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df1240cf9ccbfe9caa930075532899ad1426cfaa0c35897dc9afe55a11ee09c8?s=96&d=mm&r=g","caption":"Liisi"},"url":"https:\/\/www.meiren.ee\/de\/author\/liisi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/posts\/3059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/comments?post=3059"}],"version-history":[{"count":1,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/posts\/3059\/revisions"}],"predecessor-version":[{"id":3070,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/posts\/3059\/revisions\/3070"}],"wp:attachment":[{"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/media?parent=3059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/categories?post=3059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.meiren.ee\/de\/wp-json\/wp\/v2\/tags?post=3059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}